{"id":7120,"date":"2023-12-20T13:19:26","date_gmt":"2023-12-20T16:19:26","guid":{"rendered":"https:\/\/salvadoracontece.com.br\/?p=7120"},"modified":"2023-12-20T13:19:28","modified_gmt":"2023-12-20T16:19:28","slug":"trabalho-infantil-cresceu-de-2019-a-2022-mostra-ibge","status":"publish","type":"post","link":"https:\/\/salvadoracontece.com.br\/index.php\/2023\/12\/20\/trabalho-infantil-cresceu-de-2019-a-2022-mostra-ibge\/","title":{"rendered":"Trabalho infantil cresceu de 2019 a 2022, mostra IBGE"},"content":{"rendered":"\n<p>Depois de tr\u00eas anos seguidos de redu\u00e7\u00e3o, o trabalho infantil cresceu no Brasil entre 2019 e 2022, durante o governo de Jair Bolsonaro. No ano passado, 1,881 milh\u00e3o de pessoas de 5 a 17 anos estavam em situa\u00e7\u00e3o de trabalho infantil. O dado faz parte da Pesquisa Nacional por Amostra de Domic\u00edlios (Pnad) Cont\u00ednua sobre o Trabalho de Crian\u00e7as e Adolescentes, divulgada nesta quarta-feira (20), no Rio de Janeiro, pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). &nbsp;<\/p>\n\n\n\n<p>O levantamento \u00e9 feito desde 2016, quando o IBGE identificou 2,112 milh\u00f5es de pessoas nessa situa\u00e7\u00e3o. At\u00e9 2019, o contingente caiu seguidamente para 1,758 milh\u00e3o. Por causa da pandemia, a pesquisa n\u00e3o foi divulgada nos anos de 2020 e 2021.&nbsp;<\/p>\n\n\n\n<p>Para classificar o trabalho infantil, o IBGE segue orienta\u00e7\u00f5es da Organiza\u00e7\u00e3o Internacional do Trabalho (OIT), que o conceitua como \u201caquele que \u00e9 perigoso e prejudicial para a sa\u00fade e desenvolvimento mental, f\u00edsico, social ou moral das crian\u00e7as e que interfere na sua escolariza\u00e7\u00e3o\u201d. Acrescentam-se \u00e0 classifica\u00e7\u00e3o atividades informais e com jornadas excessivas.&nbsp;<\/p>\n\n\n\n<p>Do universo de crian\u00e7as e adolescentes no trabalho infantil, 467 mil (24%) realizavam apenas atividades de autoconsumo, como cultivo, ca\u00e7a, pesca, fabrica\u00e7\u00e3o de roupas e constru\u00e7\u00e3o de casa, entre outros exemplos.&nbsp;<\/p>\n\n\n\n<p>O que diz a lei&nbsp;<br>O IBGE estima que, no pa\u00eds, 2,1 milh\u00f5es de pessoas entre 5 e 17 anos exerciam atividades econ\u00f4micas ou para autoconsumo em 2022. A diferen\u00e7a desse n\u00famero para o universo de jovens classificados como em situa\u00e7\u00e3o de trabalho infantil (1,881 milh\u00e3o) se d\u00e1 porque nem todas as atividades nessa faixa et\u00e1ria s\u00e3o consideradas trabalho infantil.&nbsp;<\/p>\n\n\n\n<p>A legisla\u00e7\u00e3o brasileira imp\u00f5e delimita\u00e7\u00f5es. At\u00e9 os 13 anos, \u00e9 proibida qualquer forma de trabalho. De 14 a 15 anos, trabalho \u00e9 permitido apenas na forma de aprendiz. Aos 16 e 17 anos, h\u00e1 restri\u00e7\u00f5es ao trabalho noturno, insalubre e perigoso.&nbsp;<\/p>\n\n\n\n<p>Crescimento&nbsp;<br>O aumento do trabalho infantil no pa\u00eds se revelou n\u00e3o s\u00f3 em termos absolutos \u2013 ou seja, quantidade de pessoas. Houve um crescimento quando se analisa a propor\u00e7\u00e3o de crian\u00e7as e adolescentes exercendo essas atividades.&nbsp;<\/p>\n\n\n\n<p>Entre 2019 e 2022, a popula\u00e7\u00e3o com 5 a 17 anos diminuiu 1,4%, no entanto, o contingente desse grupo et\u00e1rio em situa\u00e7\u00e3o de trabalho infantil aumentou 7%.&nbsp;<\/p>\n\n\n\n<p>Em 2019, o percentual de pessoas de 5 a 17 anos que exerciam alguma forma de trabalho infantil era 4,5%. J\u00e1 em 2022 subiu para 4,9%. Isso representa praticamente um em cada 20 jovens dessa faixa et\u00e1ria.&nbsp;<\/p>\n\n\n\n<p>Faixas et\u00e1rias&nbsp;<br>Os pesquisadores do IBGE identificaram que a exist\u00eancia do trabalho infantil aumenta \u00e0 medida que a idade avan\u00e7a. No grupo de pessoas de 5 a 13 anos, essa incid\u00eancia \u00e9 de 1,7%. J\u00e1 no grupo de 14 e 15 anos, salta para 7,3%. Entre os jovens de 16 e 17 anos, a propor\u00e7\u00e3o mais que dobrava para 16,3%. &nbsp;<\/p>\n\n\n\n<p>Mais da metade de todos os trabalhadores infantis (52,5%) tinha 16 e 17 anos de idade; enquanto 23,9% tinham de 5 a 13 anos, e 23,6% tinham 14 e 15 anos.&nbsp;<\/p>\n\n\n\n<p>Ao se analisar como as faixas et\u00e1rias se comportaram no per\u00edodo em que o trabalho infantil cresceu no Brasil, ou seja, de 2019 a 2022, percebe-se que o grupo de 16 e 17 anos foi o que experimentou maior aumento. Em 2019, a incid\u00eancia era de 14,9%, enquanto em 2022 subiu para 16,3%.&nbsp;<\/p>\n\n\n\n<p>Sexo e cor&nbsp;<br>A pesquisa explicita que homens e negros s\u00e3o sobrerrepresentados nas estat\u00edsticas de trabalho infantil. Em 2022, enquanto no total da popula\u00e7\u00e3o de 5 a 17 anos os homens eram 51%, entre as crian\u00e7as e adolescentes em situa\u00e7\u00e3o de trabalho infantil a propor\u00e7\u00e3o salta para 65%. &nbsp;<\/p>\n\n\n\n<p>No quesito cor, os negros \u2013 classifica\u00e7\u00e3o que soma pretos e pardos &#8211; eram 58,8% da popula\u00e7\u00e3o de 5 a 17 anos em 2022. J\u00e1 no grupo de pessoas em situa\u00e7\u00e3o de trabalho infantil, os negros representavam 66,3%.&nbsp;<\/p>\n\n\n\n<p>Por outro lado, os brancos eram 40,3% da popula\u00e7\u00e3o de 5 a 17 anos, mas 33% entre os envolvidos com trabalho infantil.&nbsp;<\/p>\n\n\n\n<p>Informalidade&nbsp;<br>O IBGE verificou o grau de informalidade no trabalho infantil desempenhado por pessoas de 16 e 17 anos. Foram estimadas 810 mil adolescentes sem carteira assinada, o que significava uma taxa de informalidade de 76,6% &#8211; a maior da s\u00e9rie hist\u00f3rica iniciada em 2016. O menor n\u00edvel de informalidade havia sido em 2018, com 73,6%.&nbsp;<\/p>\n\n\n\n<p>O estudo revela ainda que, no universo de crian\u00e7as e adolescentes envolvidos com o trabalho infantil, a maioria (59,1%) era empregada e mais de um quarto (26,8%) tinha atividade ligada \u00e0 fam\u00edlia. Al\u00e9m disso, 14,1% trabalhavam por conta pr\u00f3pria ou como empregadores.&nbsp;<\/p>\n\n\n\n<p>Trabalho infantil cresceu no governo Bolsonaro, mostra IBGE. Foto: Arte\/EBC<br>Piores formas de trabalho infantil&nbsp;<br>A pesquisa do IBGE investigou, tamb\u00e9m, o n\u00famero de jovens submetidos a ocupa\u00e7\u00f5es que fazem parte da Lista das Piores Formas de Trabalho Infantil (Lista TIP), uma rela\u00e7\u00e3o regulamentada pelo Decreto 6.481 da Presid\u00eancia da Rep\u00fablica, de acordo com a Conven\u00e7\u00e3o 182 da Organiza\u00e7\u00e3o Internacional do Trabalho &#8211; OIT. &nbsp;<\/p>\n\n\n\n<p>A Lista TIP re\u00fane atividades desempenhadas em locais como serralherias, ind\u00fastria extrativa, esgoto, matadouros e manguezais, entre outros. S\u00e3o ocupa\u00e7\u00f5es relacionadas a intenso esfor\u00e7o f\u00edsico, calor, insalubridade e outras caracter\u00edsticas que podem causar fraturas, mutila\u00e7\u00f5es, envenenamento e outros danos aos menores de idade.&nbsp;<\/p>\n\n\n\n<p>Em 2022, eram 756 mil crian\u00e7as e adolescentes em atividades da Lista TIP, o que representava 46,2% do total de pessoas de 5 a 17 anos que realizavam atividades econ\u00f4micas (1,6 milh\u00e3o). Esse percentual vem apresentando queda desde 2016, quando era de 51,3%. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Rendimento&nbsp;<br>Em 2022, o rendimento m\u00e9dio mensal das pessoas de 5 a 17 anos que realizavam atividades econ\u00f4micas em situa\u00e7\u00e3o de trabalho infantil foi estimado em R$ 716. &nbsp;<\/p>\n\n\n\n<p>O rendimento crescia conforme a idade, partindo de R$ 246, no grupo de 5 a 13 anos, e alcan\u00e7ando R$ 799 entre as pessoas de 16 e 17 anos. &nbsp;<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 cor, o valor m\u00e9dio da popula\u00e7\u00e3o negra era de R$ 660, aumentando para R$ 817 para a de cor branca.&nbsp;<\/p>\n\n\n\n<p>Um comparativo que deixa claro o quanto o dinheiro do trabalho infantil afasta o jovem da educa\u00e7\u00e3o \u00e9 que o trabalhador infantil que ainda ia para a escola tinha renda m\u00e9dia de R$ 671. J\u00e1 o que n\u00e3o frequentava mais salas de aula tinha rendimento de R$ 931.&nbsp;<\/p>\n\n\n\n<p>Entre os adolescentes com 16 a 17 anos, 32,4% trabalhavam 40 horas ou mais por semana.&nbsp;<\/p>\n\n\n\n<p>Educa\u00e7\u00e3o&nbsp;<br>No quesito educa\u00e7\u00e3o, o percentual de 97,1% da popula\u00e7\u00e3o de 5 a 17 anos de idade era formado por estudantes em 2022, enquanto entre os trabalhadores infantis a estimativa baixava para 87,9%. No universo de 5 a 13 anos, havia uma universaliza\u00e7\u00e3o, isto \u00e9, praticamente todos (98%) frequentam a escola.&nbsp;<\/p>\n\n\n\n<p>No grupo 14 e 15 anos, a propor\u00e7\u00e3o de estudantes na popula\u00e7\u00e3o total (98,5%) era levemente superior que a do grupo de mesma idade em situa\u00e7\u00e3o de trabalho infantil (96%).&nbsp;<\/p>\n\n\n\n<p>J\u00e1 entre as pessoas de 16 e 17 anos, havia maior diferen\u00e7a. Enquanto 89,4% da popula\u00e7\u00e3o dessa faixa et\u00e1ria frequentavam escola, o \u00edndice regredia para 79,5% entre os trabalhadores infantis.&nbsp;<\/p>\n\n\n\n<p>Programas sociais&nbsp;<br>O IBGE aponta, ainda, que, em 2022, havia 582 mil pessoas de 5 a 17 anos (35,6%) que realizavam atividade econ\u00f4mica e moravam em domic\u00edlios que possu\u00edam renda proveniente de benef\u00edcios sociais do governo.&nbsp;<\/p>\n\n\n\n<p>Fonte: Agencia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de tr\u00eas anos seguidos de redu\u00e7\u00e3o, o trabalho infantil cresceu no Brasil entre 2019 e 2022, durante o governo de Jair Bolsonaro. No ano passado, 1,881 milh\u00e3o de pessoas de 5 a 17 anos estavam em situa\u00e7\u00e3o de trabalho infantil. O dado faz parte da Pesquisa Nacional por Amostra de Domic\u00edlios (Pnad) Cont\u00ednua sobre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-7120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7120"}],"version-history":[{"count":1,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7120\/revisions"}],"predecessor-version":[{"id":7122,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7120\/revisions\/7122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/media\/7121"}],"wp:attachment":[{"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salvadoracontece.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}